{"id":5179,"date":"2015-10-27T20:35:11","date_gmt":"2015-10-27T19:35:11","guid":{"rendered":"http:\/\/www.thinkingafrica.org\/V2\/?p=5179"},"modified":"2021-05-25T15:59:11","modified_gmt":"2021-05-25T13:59:11","slug":"quelles-limites-pour-le-golfe-de-guinee","status":"publish","type":"post","link":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/","title":{"rendered":"Quelles limites pour le golfe de Guin\u00e9e?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row fullwidth=\u00a0\u00bbfalse\u00a0\u00bb attached=\u00a0\u00bbfalse\u00a0\u00bb padding=\u00a0\u00bb0&Prime; visibility=\u00a0\u00bb\u00a0\u00bb animation=\u00a0\u00bb\u00a0\u00bb][vc_column border_color=\u00a0\u00bb\u00a0\u00bb visibility=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][vc_column_text disable_pattern=\u00a0\u00bbtrue\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb margin_bottom=\u00a0\u00bb0&Prime;]<em>Par Alceme Tsassa<\/em><\/p>\n<p><strong>R\u00c9SUM\u00c9:<\/strong><br \/>\nCette note passe en revue le d\u00e9bat d\u00e9finitionnel qui tourne autour des limites du golfe de Guin\u00e9e. Car jusqu\u2019\u00e0 ce jour, il n\u2019existe aucune unanimit\u00e9 sur les limites g\u00e9ographique de cet espace r\u00e9gional. La question divise beaucoup des chercheurs, notamment africains qui travaillent sur ce champ d\u2019\u00e9tude.<br \/>\nLa note est divis\u00e9e en deux grandes parties: la premi\u00e8re cherche \u00e0 comprendre les fondements du d\u00e9bat autour des limites g\u00e9ographiques de cette r\u00e9gion. Il s\u2019agit des fondements qui int\u00e8grent la g\u00e9ographie et l\u2019histoire de la zone. La deuxi\u00e8me analyse le contenu du d\u00e9bat en montrant les points de vues divergents des chercheurs sur la question des limites du golfe de Guin\u00e9e. L\u2019auteur essaie alors de fa\u00e7on synth\u00e9tique de repartir, les chercheurs selon leur approche d\u00e9finitionnelle.<br \/>\nEn conclusion, l\u2019auteur montre que toutes les d\u00e9finitions qui sont avanc\u00e9es par les chercheurs pour d\u00e9limiter le golfe de Guin\u00e9e, se r\u00e9sument dans trois sens: g\u00e9ographique, g\u00e9opolitique et institutionnelle. Et au regard de la complexit\u00e9 historique, g\u00e9ographique et politique de la r\u00e9gion, il formule des recommandations pour toute \u00e9tude visant \u00e0 aborder le golfe de Guin\u00e9e comme cadre d\u2019analyse.[\/vc_column_text][vc_separator color=\u00a0\u00bbgrey\u00a0\u00bb align=\u00a0\u00bbalign_center\u00a0\u00bb style=\u00a0\u00bbdashed\u00a0\u00bb][vc_column_text disable_pattern=\u00a0\u00bbtrue\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb margin_bottom=\u00a0\u00bb0&Prime;]<strong>PROBL\u00c9MATIQUE: <\/strong><br \/>\nCet article soul\u00e8ve une probl\u00e9matique qui tourne autour de trois questions:<br \/>\n-Qu\u2019est-ce qu\u2019on entend par golfe de Guin\u00e9e?<br \/>\n-O\u00f9 le localiser?<br \/>\n-Quels sont les pays qui le composent?<\/p>\n<p><strong>CONTEXTE DE LA NOTE:<\/strong><br \/>\nCette note s\u2019inscrit dans un contexte o\u00f9 cette r\u00e9gion fait l\u2019objet d\u2019une attention particuli\u00e8re de la part de la communaut\u00e9 internationale, en raison non seulement des convoitises qu\u2019elle suscite, mais aussi par les menaces qu\u2019elle repr\u00e9sente. Ce qui en fait un enjeu g\u00e9opolitique. C\u2019est la raison pour laquelle, une r\u00e9flexion sur les limites de cette r\u00e9gion contribuerait \u00e0 mieux comprendre les enjeux qui gravitent autour de cette r\u00e9gion.<\/p>\n<p><strong>ID\u00c9ES MAJEURES:<\/strong><br \/>\n-Le golfe de Guin\u00e9e est un espace complexe selon qu\u2019on l\u2019aborde d\u2019un point de vue historique, culturel, institutionnel, g\u00e9ographique ou g\u00e9opolitique.<br \/>\n-Le chercheur qui aborde cet espace comme champ d\u2019\u00e9tude, devrait au tout d\u00e9but de sa d\u00e9marche, souligner qu\u2019il existe plusieurs d\u00e9finitions au sujet du golfe de Guin\u00e9e<br \/>\n-Et donc choisir son angle d\u2019analyse et justifier son choix.<br \/>\n-Il serait risquer et donc arbitraire, de retenir sur toutes les d\u00e9finitions qui existent au sujet du golfe de Guin\u00e9e, une qui soit vraies; en raison des contenus divers et vari\u00e9s de cet espace.<br \/>\n[\/vc_column_text][\/vc_column][vc_column border_color=\u00a0\u00bb\u00a0\u00bb visibility=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][vc_column_text disable_pattern=\u00a0\u00bbtrue\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb margin_bottom=\u00a0\u00bb0&Prime;]<span class=\"su-highlight\" style=\"background:#ffffff;color:#970000\">&nbsp;<a href=\"http:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/11\/NAP-32-OK.pdf\"><strong>TELECHARGEZ LA NOTE D&rsquo;ANALYSE POLITIQUE EN PDF<\/strong><\/a>&nbsp;<\/span>\n<div class=\"su-document su-u-responsive-media-yes\"><iframe loading=\"lazy\" src=\"\/\/docs.google.com\/viewer?embedded=true&url=http:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/11\/NAP-32-OK.pdf\" width=\"300\" height=\"500\" class=\"su-document\" title=\"\"><\/iframe><\/div>[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row fullwidth=\u00a0\u00bbfalse\u00a0\u00bb attached=\u00a0\u00bbfalse\u00a0\u00bb padding=\u00a0\u00bb0&Prime; visibility=\u00a0\u00bb\u00a0\u00bb animation=\u00a0\u00bb\u00a0\u00bb][vc_column border_color=\u00a0\u00bb\u00a0\u00bb visibility=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][vc_column_text disable_pattern=\u00a0\u00bbtrue\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb margin_bottom=\u00a0\u00bb0&Prime;]Par Alceme Tsassa R\u00c9SUM\u00c9: Cette note passe en revue le d\u00e9bat d\u00e9finitionnel qui tourne autour des limites du golfe de Guin\u00e9e. Car jusqu\u2019\u00e0 ce jour, il n\u2019existe aucune unanimit\u00e9 sur les limites g\u00e9ographique de cet espace r\u00e9gional. La question divise beaucoup des chercheurs, notamment [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34,40,35],"tags":[279,280,277,199,278],"class_list":["post-5179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse-politique","category-gouvernance","category-securite","tag-cedeao","tag-ceeac","tag-cote-ouest-africaine","tag-golfe-de-guinee","tag-ocean-atlantique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quelles limites pour le golfe de Guin\u00e9e? - Thinking Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelles limites pour le golfe de Guin\u00e9e? - Thinking Africa\" \/>\n<meta property=\"og:description\" content=\"[vc_row fullwidth=\u00a0\u00bbfalse\u00a0\u00bb attached=\u00a0\u00bbfalse\u00a0\u00bb padding=\u00a0\u00bb0&Prime; visibility=\u00a0\u00bb\u00a0\u00bb animation=\u00a0\u00bb\u00a0\u00bb][vc_column border_color=\u00a0\u00bb\u00a0\u00bb visibility=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][vc_column_text disable_pattern=\u00a0\u00bbtrue\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb margin_bottom=\u00a0\u00bb0&Prime;]Par Alceme Tsassa R\u00c9SUM\u00c9: Cette note passe en revue le d\u00e9bat d\u00e9finitionnel qui tourne autour des limites du golfe de Guin\u00e9e. Car jusqu\u2019\u00e0 ce jour, il n\u2019existe aucune unanimit\u00e9 sur les limites g\u00e9ographique de cet espace r\u00e9gional. La question divise beaucoup des chercheurs, notamment [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/\" \/>\n<meta property=\"og:site_name\" content=\"Thinking Africa\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-27T19:35:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-25T13:59:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/10\/golfe-de-guinee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"383\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"TA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"TA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/\"},\"author\":{\"name\":\"TA\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#\\\/schema\\\/person\\\/d43605ef0d5681c1b27a4ba1fede1cf4\"},\"headline\":\"Quelles limites pour le golfe de Guin\u00e9e?\",\"datePublished\":\"2015-10-27T19:35:11+00:00\",\"dateModified\":\"2021-05-25T13:59:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/\"},\"wordCount\":562,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/golfe-de-guinee.png\",\"keywords\":[\"CEDEAO\",\"CEEAC\",\"c\u00f4te ouest africaine\",\"golfe de Guin\u00e9e\",\"oc\u00e9an atlantique\"],\"articleSection\":[\"Note d'analyse politique\",\"Politiques, strat\u00e9gies &amp; diplomaties \u00e9conomiques\",\"S\u00e9curit\u00e9, d\u00e9fense &amp; armements\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/\",\"name\":\"Quelles limites pour le golfe de Guin\u00e9e? - Thinking Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/golfe-de-guinee.png\",\"datePublished\":\"2015-10-27T19:35:11+00:00\",\"dateModified\":\"2021-05-25T13:59:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#\\\/schema\\\/person\\\/d43605ef0d5681c1b27a4ba1fede1cf4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/golfe-de-guinee.png\",\"contentUrl\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/golfe-de-guinee.png\",\"width\":608,\"height\":383},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/quelles-limites-pour-le-golfe-de-guinee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelles limites pour le golfe de Guin\u00e9e?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#website\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/\",\"name\":\"Thinking Africa\",\"description\":\"Recherche, r\u00e9flexions et ressources pour r\u00e9inventer le leadership africain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#\\\/schema\\\/person\\\/d43605ef0d5681c1b27a4ba1fede1cf4\",\"name\":\"TA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g\",\"caption\":\"TA\"},\"description\":\"Thinking Africa est un institut de recherche et d'enseignement sur la paix. R\u00e9seau de jeunes chercheurs, d\u2019universitaires confirm\u00e9s et d\u2019experts, Thinking Africa offre, aux institutions, aux gouvernements, aux soci\u00e9t\u00e9s civiles, et aux organisations, des analyses et recommandations pour vivre la paix sur le continent africain.\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelles limites pour le golfe de Guin\u00e9e? - Thinking Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelles limites pour le golfe de Guin\u00e9e? - Thinking Africa","og_description":"[vc_row fullwidth=\u00a0\u00bbfalse\u00a0\u00bb attached=\u00a0\u00bbfalse\u00a0\u00bb padding=\u00a0\u00bb0&Prime; visibility=\u00a0\u00bb\u00a0\u00bb animation=\u00a0\u00bb\u00a0\u00bb][vc_column border_color=\u00a0\u00bb\u00a0\u00bb visibility=\u00a0\u00bb\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][vc_column_text disable_pattern=\u00a0\u00bbtrue\u00a0\u00bb align=\u00a0\u00bbleft\u00a0\u00bb margin_bottom=\u00a0\u00bb0&Prime;]Par Alceme Tsassa R\u00c9SUM\u00c9: Cette note passe en revue le d\u00e9bat d\u00e9finitionnel qui tourne autour des limites du golfe de Guin\u00e9e. Car jusqu\u2019\u00e0 ce jour, il n\u2019existe aucune unanimit\u00e9 sur les limites g\u00e9ographique de cet espace r\u00e9gional. La question divise beaucoup des chercheurs, notamment [&hellip;]","og_url":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/","og_site_name":"Thinking Africa","article_published_time":"2015-10-27T19:35:11+00:00","article_modified_time":"2021-05-25T13:59:11+00:00","og_image":[{"width":608,"height":383,"url":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/10\/golfe-de-guinee.png","type":"image\/png"}],"author":"TA","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"TA","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#article","isPartOf":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/"},"author":{"name":"TA","@id":"https:\/\/www.thinkingafrica.org\/V2\/#\/schema\/person\/d43605ef0d5681c1b27a4ba1fede1cf4"},"headline":"Quelles limites pour le golfe de Guin\u00e9e?","datePublished":"2015-10-27T19:35:11+00:00","dateModified":"2021-05-25T13:59:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/"},"wordCount":562,"commentCount":0,"image":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/10\/golfe-de-guinee.png","keywords":["CEDEAO","CEEAC","c\u00f4te ouest africaine","golfe de Guin\u00e9e","oc\u00e9an atlantique"],"articleSection":["Note d'analyse politique","Politiques, strat\u00e9gies &amp; diplomaties \u00e9conomiques","S\u00e9curit\u00e9, d\u00e9fense &amp; armements"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/","url":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/","name":"Quelles limites pour le golfe de Guin\u00e9e? - Thinking Africa","isPartOf":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#primaryimage"},"image":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/10\/golfe-de-guinee.png","datePublished":"2015-10-27T19:35:11+00:00","dateModified":"2021-05-25T13:59:11+00:00","author":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/#\/schema\/person\/d43605ef0d5681c1b27a4ba1fede1cf4"},"breadcrumb":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#primaryimage","url":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/10\/golfe-de-guinee.png","contentUrl":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2015\/10\/golfe-de-guinee.png","width":608,"height":383},{"@type":"BreadcrumbList","@id":"https:\/\/www.thinkingafrica.org\/V2\/quelles-limites-pour-le-golfe-de-guinee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thinkingafrica.org\/V2\/"},{"@type":"ListItem","position":2,"name":"Quelles limites pour le golfe de Guin\u00e9e?"}]},{"@type":"WebSite","@id":"https:\/\/www.thinkingafrica.org\/V2\/#website","url":"https:\/\/www.thinkingafrica.org\/V2\/","name":"Thinking Africa","description":"Recherche, r\u00e9flexions et ressources pour r\u00e9inventer le leadership africain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thinkingafrica.org\/V2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.thinkingafrica.org\/V2\/#\/schema\/person\/d43605ef0d5681c1b27a4ba1fede1cf4","name":"TA","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g","caption":"TA"},"description":"Thinking Africa est un institut de recherche et d'enseignement sur la paix. R\u00e9seau de jeunes chercheurs, d\u2019universitaires confirm\u00e9s et d\u2019experts, Thinking Africa offre, aux institutions, aux gouvernements, aux soci\u00e9t\u00e9s civiles, et aux organisations, des analyses et recommandations pour vivre la paix sur le continent africain.","url":"https:\/\/www.thinkingafrica.org\/V2\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts\/5179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/comments?post=5179"}],"version-history":[{"count":3,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts\/5179\/revisions"}],"predecessor-version":[{"id":5225,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts\/5179\/revisions\/5225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/media\/5180"}],"wp:attachment":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/media?parent=5179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/categories?post=5179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/tags?post=5179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}