{"id":7115,"date":"2020-02-27T13:08:25","date_gmt":"2020-02-27T12:08:25","guid":{"rendered":"http:\/\/www.thinkingafrica.org\/V2\/?p=7115"},"modified":"2021-05-25T15:52:24","modified_gmt":"2021-05-25T13:52:24","slug":"imaginer-un-devenir-en-commun","status":"publish","type":"post","link":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/","title":{"rendered":"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row padding=\u00a0\u00bb0&Prime;][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<em>Par Louis Nana<\/em><\/p>\n<p><strong>R\u00c9SUM\u00c9:<\/strong><br \/>\nLe contexte mondial est marqu\u00e9 par un paradoxe : \u00e0 mesure que la configuration du monde en appelle \u00e0 plus d\u2019ouverture, on assiste, ici et l\u00e0, \u00e0 un repli identitaire et \u00e0 l\u2019exacerbation des identit\u00e9s nationales. Dans un tel contexte, la question de comment vivre-ensemble, ce que cela signifie, exige ou implique est cruciale. D\u2019o\u00f9 la n\u00e9cessit\u00e9 de penser le concept de l\u2019en-commun, qui suscite davantage d\u2019int\u00e9r\u00eat. Loin d\u2019\u00e9puiser une telle question, cette note vise surtout \u00e0 partager, et \u00e0 soumettre \u00e0 la discussion, une approche du concept de la Communaut\u00e9 dans la litt\u00e9rature, \u00e0 partir du concept de l\u2019en-commun, appr\u00e9hend\u00e9 ici comme principe au c\u0153ur de tout projet &#8211; ou pens\u00e9e &#8211; de la Communaut\u00e9. Il ne s\u2019agit pas, ici, de faire une pr\u00e9sentation g\u00e9n\u00e9rale de la discussion autour du concept, notamment dans le champ de la philosophie. L\u2019interrogation qui nous int\u00e9resse est plut\u00f4t la suivante : comment penser l\u2019en-commun \u00e0 partir de la litt\u00e9rature \u2014 du roman, pr\u00e9cis\u00e9ment ?<\/p>\n[\/vc_column_text][vc_separator style=\u00a0\u00bbdashed\u00a0\u00bb][vc_column_text]<strong>CONTEXTE: <\/strong><br \/>\nLe contexte de cette note se situe \u00e0 trois niveaux. Sur le plan mondial, il est marqu\u00e9 par un paradoxe : \u00e0 mesure que les circulations s\u2019intensifient, du fait des avanc\u00e9es technologiques notamment, on assiste \u00e0 des replis identitaires, soutenus par la peur de se perdre, ou d\u2019\u00eatre \u00ab\u00a0remplac\u00e9\u00a0\u00bb. Pour l\u2019exprimer autrement : dans un contexte de radicale ouverture du monde, surgit paradoxalement une logique d\u2019enclos. Le plan acad\u00e9mique, quant \u00e0 lui, est marqu\u00e9 par un int\u00e9r\u00eat pour des th\u00e9ories autre qu\u2019occidentales : ce que l\u2019on appelle les th\u00e9ories du Sud global. Sur le plan sp\u00e9cifique de la sc\u00e8ne intellectuelle africaine, cette note intervient alors que des appels sont lanc\u00e9s pour le renouvellement de la pens\u00e9e \u00e0 partir de l\u2019Afrique. Ce renouvellement de la pens\u00e9e concerne aussi bien la mani\u00e8re d\u2019habiter le monde que la r\u00e9int\u00e9gration d\u2019une cat\u00e9gorie temporelle comme le futur dans les r\u00e9flexions sur notre monde, surtout sur l\u2019Afrique.<\/p>\n<p><strong>PROBL\u00c9MATIQUE: <\/strong><br \/>\nComment penser l\u2019en-commun \u00e0 partir de la litt\u00e9rature africaine contemporaine ? Quelles possibilit\u00e9s l\u2019approche centr\u00e9e sur le temps et le sujet offre-t-elle dans cette r\u00e9flexion ?<\/p>\n<p><strong>IDEES MAJEURES : <\/strong><br \/>\n&#8211; Le temps de l\u2019enchev\u00eatrement (Achille Mbembe) qui caract\u00e9rise notre \u00e9poque se traduit, dans l\u2019Afrique postcoloniale, par un ensemble d\u2019\u00e9v\u00e9nements qu\u2019il convient de d\u00e9signer comme le temps de l\u2019ombre.<br \/>\n&#8211; Le temps de l\u2019ombre est repr\u00e9sent\u00e9, dans les romans de L\u00e9onora Miano, par les m\u00e9taphores de la nuit, de l\u2019ombre et des ombres, du fant\u00f4me, de la for\u00eat, etc., pour traduire la violence qui fait de l\u2019Afrique contemporaine une Afrodystopie (Joseph Tonda).<br \/>\n&#8211; \u00c9voluant dans un tel cadre, le sujet africain postcolonial est un sujet bless\u00e9. Il fait l\u2019exp\u00e9rience de sa propre individualit\u00e9 et, par cons\u00e9quent, de l\u2019\u00eatre-avec sous le prisme de la blessure. Ainsi, toute tentative de vivre en communaut\u00e9, de pr\u00e9server la communaut\u00e9, ou d\u2019en cr\u00e9er une nouvelle est marqu\u00e9e et hant\u00e9e par cette blessure.<br \/>\n&#8211; Mais la blessure, elle-m\u00eame, ne peut \u00eatre saisie que si on la consid\u00e8re dans son rapport avec le temps. En effet, elle est, avant tout, le fruit des \u00e9v\u00e9nements qui inaugur\u00e8rent le temps de l\u2019enchev\u00eatrement (l\u2019esclavage, la Traite n\u00e9gri\u00e8re) ; ensuite, elle persiste \u00e0 cause du rapport coupable qu\u2019une \u00e9poque entretient avec celles qui sont pass\u00e9es \u2014 \u00e0 travers notamment l\u2019oubli.<br \/>\n&#8211; La lecture des romans sugg\u00e8re qu\u2019il peut y avoir un au-del\u00e0 de la blessure, et que le r\u00eave d\u2019un en-commun est possible sur le continent africain. Pour cela, il faut imaginer une utopie (une Afrotopie), comme celle du Katiopa unifi\u00e9. Celle-ci, si elle n\u2019apporte pas des r\u00e9ponses claires \u00e0 toutes les questions que peut soulever la question de la communaut\u00e9 en Afrique, permet d\u2019y r\u00e9fl\u00e9chir dans un contexte marqu\u00e9 non plus par la blessure, mais par la gu\u00e9rison, la restauration.<\/p>\n[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<span class=\"su-highlight\" style=\"background:#ffffff;color:#970000\">&nbsp;<a href=\"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/ndr-42-ok.pdf\"><strong>TELECHARGEZ LA NOTE DE RECHERCHE EN PDF<\/strong><\/a>&nbsp;<\/span>\n<div class=\"su-document su-u-responsive-media-yes\"><iframe loading=\"lazy\" src=\"\/\/docs.google.com\/viewer?embedded=true&url=https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/ndr-42-ok.pdf\" width=\"300\" height=\"500\" class=\"su-document\" title=\"\"><\/iframe><\/div>[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row padding=\u00a0\u00bb0&Prime;][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]Par Louis Nana R\u00c9SUM\u00c9: Le contexte mondial est marqu\u00e9 par un paradoxe : \u00e0 mesure que la configuration du monde en appelle \u00e0 plus d\u2019ouverture, on assiste, ici et l\u00e0, \u00e0 un repli identitaire et \u00e0 l\u2019exacerbation des identit\u00e9s nationales. Dans un tel contexte, la question de comment vivre-ensemble, ce que cela signifie, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[37,23],"tags":[],"class_list":["post-7115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mediation","category-note-recherche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano - Thinking Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano - Thinking Africa\" \/>\n<meta property=\"og:description\" content=\"[vc_row padding=\u00a0\u00bb0&Prime;][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]Par Louis Nana R\u00c9SUM\u00c9: Le contexte mondial est marqu\u00e9 par un paradoxe : \u00e0 mesure que la configuration du monde en appelle \u00e0 plus d\u2019ouverture, on assiste, ici et l\u00e0, \u00e0 un repli identitaire et \u00e0 l\u2019exacerbation des identit\u00e9s nationales. Dans un tel contexte, la question de comment vivre-ensemble, ce que cela signifie, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/\" \/>\n<meta property=\"og:site_name\" content=\"Thinking Africa\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-27T12:08:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-25T13:52:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/miano1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"TA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/\"},\"author\":{\"name\":\"TA\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#\\\/schema\\\/person\\\/d43605ef0d5681c1b27a4ba1fede1cf4\"},\"headline\":\"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano\",\"datePublished\":\"2020-02-27T12:08:25+00:00\",\"dateModified\":\"2021-05-25T13:52:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/\"},\"wordCount\":774,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/miano1.jpg\",\"articleSection\":[\"Conflits, droits &amp; justice\",\"Note de recherche\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/\",\"name\":\"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano - Thinking Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/miano1.jpg\",\"datePublished\":\"2020-02-27T12:08:25+00:00\",\"dateModified\":\"2021-05-25T13:52:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#\\\/schema\\\/person\\\/d43605ef0d5681c1b27a4ba1fede1cf4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/miano1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/miano1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/imaginer-un-devenir-en-commun\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#website\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/\",\"name\":\"Thinking Africa\",\"description\":\"Recherche, r\u00e9flexions et ressources pour r\u00e9inventer le leadership africain\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/#\\\/schema\\\/person\\\/d43605ef0d5681c1b27a4ba1fede1cf4\",\"name\":\"TA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g\",\"caption\":\"TA\"},\"description\":\"Thinking Africa est un institut de recherche et d'enseignement sur la paix. R\u00e9seau de jeunes chercheurs, d\u2019universitaires confirm\u00e9s et d\u2019experts, Thinking Africa offre, aux institutions, aux gouvernements, aux soci\u00e9t\u00e9s civiles, et aux organisations, des analyses et recommandations pour vivre la paix sur le continent africain.\",\"url\":\"https:\\\/\\\/www.thinkingafrica.org\\\/V2\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano - Thinking Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/","og_locale":"fr_FR","og_type":"article","og_title":"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano - Thinking Africa","og_description":"[vc_row padding=\u00a0\u00bb0&Prime;][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]Par Louis Nana R\u00c9SUM\u00c9: Le contexte mondial est marqu\u00e9 par un paradoxe : \u00e0 mesure que la configuration du monde en appelle \u00e0 plus d\u2019ouverture, on assiste, ici et l\u00e0, \u00e0 un repli identitaire et \u00e0 l\u2019exacerbation des identit\u00e9s nationales. Dans un tel contexte, la question de comment vivre-ensemble, ce que cela signifie, [&hellip;]","og_url":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/","og_site_name":"Thinking Africa","article_published_time":"2020-02-27T12:08:25+00:00","article_modified_time":"2021-05-25T13:52:24+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/miano1.jpg","type":"image\/jpeg"}],"author":"TA","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"TA","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#article","isPartOf":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/"},"author":{"name":"TA","@id":"https:\/\/www.thinkingafrica.org\/V2\/#\/schema\/person\/d43605ef0d5681c1b27a4ba1fede1cf4"},"headline":"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano","datePublished":"2020-02-27T12:08:25+00:00","dateModified":"2021-05-25T13:52:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/"},"wordCount":774,"commentCount":0,"image":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/miano1.jpg","articleSection":["Conflits, droits &amp; justice","Note de recherche"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/","url":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/","name":"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano - Thinking Africa","isPartOf":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#primaryimage"},"image":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/miano1.jpg","datePublished":"2020-02-27T12:08:25+00:00","dateModified":"2021-05-25T13:52:24+00:00","author":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/#\/schema\/person\/d43605ef0d5681c1b27a4ba1fede1cf4"},"breadcrumb":{"@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#primaryimage","url":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/miano1.jpg","contentUrl":"https:\/\/www.thinkingafrica.org\/V2\/wp-content\/uploads\/2020\/02\/miano1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.thinkingafrica.org\/V2\/imaginer-un-devenir-en-commun\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thinkingafrica.org\/V2\/"},{"@type":"ListItem","position":2,"name":"Imaginer un devenir-en-commun. Penser l\u2019en-commun \u00e0 travers quelques romans de L\u00e9onora Miano"}]},{"@type":"WebSite","@id":"https:\/\/www.thinkingafrica.org\/V2\/#website","url":"https:\/\/www.thinkingafrica.org\/V2\/","name":"Thinking Africa","description":"Recherche, r\u00e9flexions et ressources pour r\u00e9inventer le leadership africain","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thinkingafrica.org\/V2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.thinkingafrica.org\/V2\/#\/schema\/person\/d43605ef0d5681c1b27a4ba1fede1cf4","name":"TA","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c005dccdd1d09c481deffc8260557ebd4ca64fcb9b827c2d0426e626336abdf?s=96&d=mm&r=g","caption":"TA"},"description":"Thinking Africa est un institut de recherche et d'enseignement sur la paix. R\u00e9seau de jeunes chercheurs, d\u2019universitaires confirm\u00e9s et d\u2019experts, Thinking Africa offre, aux institutions, aux gouvernements, aux soci\u00e9t\u00e9s civiles, et aux organisations, des analyses et recommandations pour vivre la paix sur le continent africain.","url":"https:\/\/www.thinkingafrica.org\/V2\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts\/7115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/comments?post=7115"}],"version-history":[{"count":4,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts\/7115\/revisions"}],"predecessor-version":[{"id":7871,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/posts\/7115\/revisions\/7871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/media\/7121"}],"wp:attachment":[{"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/media?parent=7115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/categories?post=7115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thinkingafrica.org\/V2\/wp-json\/wp\/v2\/tags?post=7115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}